{"id":50519,"date":"2025-04-08T15:06:33","date_gmt":"2025-04-08T15:06:33","guid":{"rendered":"https:\/\/sprint-2.vadrouille.wokine.dev\/produit\/chambord-19\/"},"modified":"2025-05-12T16:25:34","modified_gmt":"2025-05-12T16:25:34","slug":"chambord-19","status":"publish","type":"product","link":"https:\/\/sprint-4.vadrouille.wokine.dev\/en\/product\/chambord-19\/","title":{"rendered":"Chambord"},"content":{"rendered":"<p>Avec la d\u00e9marche Vadrouille, vous mettez en mouvement cette paire de chaussures Paraboot.<\/p>\n<p>Ces chaussures d&#8217;occasion, entretenues avec soin par l&#8217;\u00e9quipe Vadrouille, vivront avec vous le temps d&#8217;une autre vie.<\/p>\n<p>En achetant cette paire de derbies de chez Paraboot en seconde main, vous faites une belle action.<\/p>\n","protected":false},"excerpt":{"rendered":"<h2><strong>La Chambord de Paraboot,  le golf v\u00e9ritable<\/strong><\/h2>\n<p>\nLa Chambord est un mod\u00e8le golf, un derby vintage qui <strong>convient autant aux hommes qu&#8217;aux femmes<\/strong>. Ce derby unique par ses particularit\u00e9s s\u00e9duit depuis des ann\u00e9es les amateurs de  chaussures Paraboot.\n<\/p>\n<p>\nCe soulier incarne l&#8217;essence des magnifiques ch\u00e2teaux de la Loire. Ce Golf se distingue par sa finition du plateau \u00e0 un angle de 45 degr\u00e9s, t\u00e9moignant du savoir-faire exceptionnel de la marque. Gr\u00e2ce \u00e0 sa conception et sa forme, ce mod\u00e8le convient parfaitement aux pieds fins.\n<\/p>\n<h3><strong>Pr\u00e9cisions sur la chaussure :<\/strong><\/h3>\n<p>\nCes beaux souliers sont en cuir lisse de couleur Marron. De taille 5,5 elle arbore une semelle cousue Norv\u00e9gien. Un montage que l&#8217;on retrouve rarement car plus complexe. Associant la couture \u00e0 intercalaire, le collage gomme qui s&#8217;ajoute vous assurera une paire plus que r\u00e9parable.\n<\/p>\n<h3><strong>Besoin d&#8217;un coup de main ?<\/strong><\/h3>\n<\/p>\n<p>Retrouvez pleins d&#8217;astuces pour entretenir vos paires.<\/p>\n<p>Profitez du guide des tailles pour d\u00e9terminer la bonne pointure pour vos pieds.<\/p>\n<p>Nous sommes disponibles par message et par mail pour vous renseigner.<\/p>\n<p>Mail : jevadrouille.com@gmail.com<\/p>\n<p>T\u00e9l\u00e9phone : 07 49 22 89 11<\/p>\n<p><h3><strong>Dites nous ce que vous pensez de Vadrouille !<\/strong><\/h3>\n<p>\nVenez jeter un \u0153il \u00e0 la boutique Paraboot et profitez de tous les avantages, <strong>prix r\u00e9duits, livraison offerte, produits offerts<\/strong>. Vous en vouliez encore plus ? Alors partagez-nous vos id\u00e9es.\n<\/p>\n<p> Sp\u00e9cifications techniques ref A1865 &#8211;> Pour plus d\u2019informations et d\u00e9tails<br \/>\ncontactez nous : 07 49 22 89 11<\/p>\n","protected":false},"featured_media":50448,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[17,50],"product_tag":[],"class_list":{"0":"post-50519","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chaussures","7":"product_cat-paraboot","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paraboot Chambord - Vadrouille<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paraboot Chambord - Vadrouille\" \/>\n<meta property=\"og:description\" content=\"La Chambord de Paraboot, le golf v\u00e9ritable    La Chambord est un mod\u00e8le golf, un derby vintage qui convient autant aux hommes qu&#039;aux femmes. Ce derby unique par ses particularit\u00e9s s\u00e9duit depuis des ann\u00e9es les amateurs de chaussures Paraboot.    Ce soulier incarne l&#039;essence des magnifiques ch\u00e2teaux de la Loire. Ce Golf se distingue par sa finition du plateau \u00e0 un angle de 45 degr\u00e9s, t\u00e9moignant du savoir-faire exceptionnel de la marque. Gr\u00e2ce \u00e0 sa conception et sa forme, ce mod\u00e8le convient parfaitement aux pieds fins.  Pr\u00e9cisions sur la chaussure :    Ces beaux souliers sont en cuir lisse de couleur Marron. De taille 5,5 elle arbore une semelle cousue Norv\u00e9gien. Un montage que l&#039;on retrouve rarement car plus complexe. Associant la couture \u00e0 intercalaire, le collage gomme qui s&#039;ajoute vous assurera une paire plus que r\u00e9parable.  Besoin d&#039;un coup de main ?     Retrouvez pleins d&#039;astuces pour entretenir vos paires.  Profitez du guide des tailles pour d\u00e9terminer la bonne pointure pour vos pieds.  Nous sommes disponibles par message et par mail pour vous renseigner.  Mail : jevadrouille.com@gmail.com  T\u00e9l\u00e9phone : 07 49 22 89 11   Dites nous ce que vous pensez de Vadrouille !    Venez jeter un \u0153il \u00e0 la boutique Paraboot et profitez de tous les avantages, prix r\u00e9duits, livraison offerte, produits offerts. Vous en vouliez encore plus ? Alors partagez-nous vos id\u00e9es.  Sp\u00e9cifications techniques ref A1865 --&gt; Pour plus d\u2019informations et d\u00e9tails contactez nous : 07 49 22 89 11\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Vadrouille\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-12T16:25:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sprint-4.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/04\/A1865-1.JPG-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/\",\"url\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/\",\"name\":\"Paraboot Chambord - Vadrouille\",\"isPartOf\":{\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/04\/A1865-1.JPG-scaled.webp\",\"datePublished\":\"2025-04-08T15:06:33+00:00\",\"dateModified\":\"2025-05-12T16:25:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/#primaryimage\",\"url\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/04\/A1865-1.JPG-scaled.webp\",\"contentUrl\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/04\/A1865-1.JPG-scaled.webp\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chambord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/#website\",\"url\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/\",\"name\":\"Vadrouille\",\"description\":\"Achetez vos chaussures haut de gamme reconditionn\u00e9es\",\"publisher\":{\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/#organization\",\"name\":\"Vadrouille\",\"url\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png\",\"contentUrl\":\"https:\/\/sprint-2.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png\",\"width\":1613,\"height\":617,\"caption\":\"Vadrouille\"},\"image\":{\"@id\":\"https:\/\/sprint-4.vadrouille.wokine.dev\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paraboot Chambord - Vadrouille","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/","og_locale":"en_US","og_type":"article","og_title":"Paraboot Chambord - Vadrouille","og_description":"La Chambord de Paraboot, le golf v\u00e9ritable    La Chambord est un mod\u00e8le golf, un derby vintage qui convient autant aux hommes qu'aux femmes. Ce derby unique par ses particularit\u00e9s s\u00e9duit depuis des ann\u00e9es les amateurs de chaussures Paraboot.    Ce soulier incarne l'essence des magnifiques ch\u00e2teaux de la Loire. Ce Golf se distingue par sa finition du plateau \u00e0 un angle de 45 degr\u00e9s, t\u00e9moignant du savoir-faire exceptionnel de la marque. Gr\u00e2ce \u00e0 sa conception et sa forme, ce mod\u00e8le convient parfaitement aux pieds fins.  Pr\u00e9cisions sur la chaussure :    Ces beaux souliers sont en cuir lisse de couleur Marron. De taille 5,5 elle arbore une semelle cousue Norv\u00e9gien. Un montage que l'on retrouve rarement car plus complexe. Associant la couture \u00e0 intercalaire, le collage gomme qui s'ajoute vous assurera une paire plus que r\u00e9parable.  Besoin d'un coup de main ?     Retrouvez pleins d'astuces pour entretenir vos paires.  Profitez du guide des tailles pour d\u00e9terminer la bonne pointure pour vos pieds.  Nous sommes disponibles par message et par mail pour vous renseigner.  Mail : jevadrouille.com@gmail.com  T\u00e9l\u00e9phone : 07 49 22 89 11   Dites nous ce que vous pensez de Vadrouille !    Venez jeter un \u0153il \u00e0 la boutique Paraboot et profitez de tous les avantages, prix r\u00e9duits, livraison offerte, produits offerts. Vous en vouliez encore plus ? Alors partagez-nous vos id\u00e9es.  Sp\u00e9cifications techniques ref A1865 --> Pour plus d\u2019informations et d\u00e9tails contactez nous : 07 49 22 89 11","og_url":"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/","og_site_name":"Vadrouille","article_modified_time":"2025-05-12T16:25:34+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/sprint-4.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/04\/A1865-1.JPG-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/","url":"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/","name":"Paraboot Chambord - Vadrouille","isPartOf":{"@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/#primaryimage"},"image":{"@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/#primaryimage"},"thumbnailUrl":"https:\/\/sprint-4.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/04\/A1865-1.JPG-scaled.webp","datePublished":"2025-04-08T15:06:33+00:00","dateModified":"2025-05-12T16:25:34+00:00","breadcrumb":{"@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/#primaryimage","url":"https:\/\/sprint-4.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/04\/A1865-1.JPG-scaled.webp","contentUrl":"https:\/\/sprint-4.vadrouille.wokine.dev\/wp-content\/uploads\/2025\/04\/A1865-1.JPG-scaled.webp","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/produit\/chambord-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sprint-4.vadrouille.wokine.dev\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/sprint-4.vadrouille.wokine.dev\/boutique\/"},{"@type":"ListItem","position":3,"name":"Chambord"}]},{"@type":"WebSite","@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/#website","url":"https:\/\/sprint-4.vadrouille.wokine.dev\/","name":"Vadrouille","description":"Achetez vos chaussures haut de gamme reconditionn\u00e9es","publisher":{"@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sprint-4.vadrouille.wokine.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/#organization","name":"Vadrouille","url":"https:\/\/sprint-4.vadrouille.wokine.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/#\/schema\/logo\/image\/","url":"https:\/\/sprint-2.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png","contentUrl":"https:\/\/sprint-2.vadrouille.wokine.dev\/wp-content\/uploads\/2023\/02\/LOGO_VADROUILLE_Q.png","width":1613,"height":617,"caption":"Vadrouille"},"image":{"@id":"https:\/\/sprint-4.vadrouille.wokine.dev\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sprint-4.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product\/50519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sprint-4.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sprint-4.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sprint-4.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/comments?post=50519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sprint-4.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/media\/50448"}],"wp:attachment":[{"href":"https:\/\/sprint-4.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/media?parent=50519"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sprint-4.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product_brand?post=50519"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sprint-4.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product_cat?post=50519"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sprint-4.vadrouille.wokine.dev\/en\/wp-json\/wp\/v2\/product_tag?post=50519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}